{"id":40744,"date":"2024-03-11T17:21:54","date_gmt":"2024-03-11T23:21:54","guid":{"rendered":"https:\/\/noticias.ulsaoaxaca.edu.mx\/?p=40744"},"modified":"2024-03-11T17:21:54","modified_gmt":"2024-03-11T23:21:54","slug":"juntos-por-la-salud-infantil-equipo-de-erasmus-cielo-comparte-avances-en-reunion-virtual","status":"publish","type":"post","link":"https:\/\/noticias.ulsaoaxaca.edu.mx\/index.php\/2024\/03\/11\/juntos-por-la-salud-infantil-equipo-de-erasmus-cielo-comparte-avances-en-reunion-virtual\/","title":{"rendered":"Juntos por la salud infantil: Equipo de ERASMUS+ CIELO comparte avances en reuni\u00f3n virtual\u00a0"},"content":{"rendered":"\n<p><a href=\"https:\/\/noticias.ulsaoaxaca.edu.mx\/wp-content\/uploads\/2024\/03\/ERASMUS.jpg\" class=\"light\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-large wp-image-40745\" src=\"https:\/\/noticias.ulsaoaxaca.edu.mx\/wp-content\/uploads\/2024\/03\/ERASMUS-1024x683.jpg\" alt=\"\" width=\"1024\" height=\"683\" srcset=\"https:\/\/noticias.ulsaoaxaca.edu.mx\/wp-content\/uploads\/2024\/03\/ERASMUS-1024x683.jpg 1024w, https:\/\/noticias.ulsaoaxaca.edu.mx\/wp-content\/uploads\/2024\/03\/ERASMUS-300x200.jpg 300w, https:\/\/noticias.ulsaoaxaca.edu.mx\/wp-content\/uploads\/2024\/03\/ERASMUS-768x512.jpg 768w, https:\/\/noticias.ulsaoaxaca.edu.mx\/wp-content\/uploads\/2024\/03\/ERASMUS-800x533.jpg 800w, https:\/\/noticias.ulsaoaxaca.edu.mx\/wp-content\/uploads\/2024\/03\/ERASMUS.jpg 1200w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/a><span data-contrast=\"none\">Colaboradores de las 12 universidades que desarrollan el proyecto ERASMUS+ CIELO tuvieron su segunda reuni\u00f3n virtual para compartir avances de la propuesta que busca mejorar la salud infantil en Am\u00e9rica Latina a trav\u00e9s de la capacitaci\u00f3n a estudiantes, profesores y profesionales de la salud en Instituciones de Educaci\u00f3n Superior. <\/span><span data-ccp-props=\"{&quot;335551550&quot;:6,&quot;335551620&quot;:6}\">\u00a0<\/span><\/p>\n<p style=\"text-align: justify;\"><span data-contrast=\"none\">En tres sesiones online, participaron los gestores de cada una de las universidades y abordaron tem\u00e1ticas relacionadas con la organizaci\u00f3n administrativa y econ\u00f3mica presupuestaria del proyecto.<\/span><\/p>\n<p style=\"text-align: justify;\"><span data-contrast=\"none\">En esta ocasi\u00f3n, el primer d\u00eda la <\/span><span data-contrast=\"auto\">Universidad Tecnol\u00f3gica de Riga de Letonia<\/span><span data-contrast=\"auto\">, encargada de la gesti\u00f3n administrativa del proyecto, present\u00f3 los momentos y formatos que se deben entregar como evidencia del trabajo que se ha desarrollado desde julio del 2023, cuando fue aprobado el proyecto.<\/span>\u00a0<\/p>\n<p style=\"text-align: justify;\"><span data-contrast=\"none\">El siguiente d\u00eda, la Universidad Cat\u00f3lica Silva Henr\u00edquez expuso lo que se ha logrado en relaci\u00f3n con la obtenci\u00f3n de los permisos entregados por los Comit\u00e9s de \u00c9tica Cient\u00edficos (CEC) respectivos de cada una de las Universidades, para la aplicaci\u00f3n de cuestionarios para profesionales de la salud y docentes universitarios; as\u00ed como tambi\u00e9n la log\u00edstica para la aplicaci\u00f3n de cuestionarios y el desarrollo de los grupos focales para estudiantes universitarios.\u00a0<\/span><span data-ccp-props=\"{&quot;335551550&quot;:6,&quot;335551620&quot;:6}\">\u00a0<\/span><\/p>\n<p style=\"text-align: justify;\"><span data-contrast=\"none\">\u201cLa aplicaci\u00f3n de estos instrumentos nos permitir\u00e1 conocer, por ejemplo, cu\u00e1nto saben los docentes y estudiantes universitarios, as\u00ed como tambi\u00e9n los profesionales de la salud, sobre la obesidad, as\u00ed como tambi\u00e9n su actitud hacia las personas obesas, lo cual es clave para la construcci\u00f3n del curso online y la aplicaci\u00f3n m\u00f3vil\u201d, dijo el Dr. Sebasti\u00e1n Loyola Arroyo, acad\u00e9mico investigador de la Facultad de Ciencias de la Salud UCSH; cabe destacar que esta instituci\u00f3n ya cuenta con su protocolo de trabajo aprobado por el CEC, as\u00ed como tambi\u00e9n la Universidad Del Alba, ambas universidades de Chile, y se encuentra en proceso de aprobaci\u00f3n en los organismos espec\u00edficos de los pa\u00edses de Costa Rica y M\u00e9xico.<\/span><span data-ccp-props=\"{&quot;335551550&quot;:6,&quot;335551620&quot;:6}\">\u00a0<\/span><\/p>\n<p style=\"text-align: justify;\"><span data-contrast=\"none\">El \u00faltimo d\u00eda, la Universidad La Salle Noroeste present\u00f3 el Plan de Difusi\u00f3n y Comunicaci\u00f3n de ERASMUS+ CIELO, compartiendo el enlace del sitio web en el que se podr\u00e1 obtener m\u00e1s informaci\u00f3n de las actividades, eventos y avances del proyecto.\u00a0<\/span><span data-ccp-props=\"{&quot;335551550&quot;:6,&quot;335551620&quot;:6}\">\u00a0<\/span><\/p>\n<p style=\"text-align: justify;\"><span data-contrast=\"none\">A lo largo de esta reuni\u00f3n se discutieron adem\u00e1s temas relacionados con la b\u00fasqueda bibliogr\u00e1fica con base en los futuros resultados de los cuestionarios y grupos focales, la generaci\u00f3n de la estructura del curso online y el equipamiento con el que el programa ERASMUS + apoyar\u00e1 a cada HEI.<\/span><span data-ccp-props=\"{&quot;335551550&quot;:6,&quot;335551620&quot;:6}\">\u00a0<\/span><\/p>\n<p style=\"text-align: justify;\"><span data-contrast=\"none\">Se program\u00f3 para el pr\u00f3ximo 7, 8 y 9 de mayo la reuni\u00f3n presencial que se llevar\u00e1 a cabo en la Universidad Cat\u00f3lica Silva Henr\u00edquez en Santiago de Chile, para continuar con la evaluaci\u00f3n del progreso del proyecto.<\/span><span data-ccp-props=\"{&quot;335551550&quot;:6,&quot;335551620&quot;:6}\">\u00a0<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Despu\u00e9s de la primera sesi\u00f3n virtual que se celebr\u00f3 en septiembre de 2023 para presentar a las universidades participantes, los colaboradores se volvieron a reunir para compartir el progreso del proyecto ERASMUS+ CIELO\u00a0\u00a0<\/p>\n","protected":false},"author":12,"featured_media":40745,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[414,31],"tags":[45,119],"class_list":["post-40744","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-investigacion","category-noticias","tag-investigacion","tag-licenciatura"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Juntos por la salud infantil: Equipo de ERASMUS+ CIELO comparte avances en reuni\u00f3n virtual\u00a0 - Noticias La Salle Oaxaca<\/title>\n<meta name=\"description\" content=\"Colaboradores de las 12 universidades que desarrollan el proyecto ERASMUS+ CIELO tuvieron su segunda reuni\u00f3n virtual para compartir avances de la propuesta que busca mejorar la salud infantil en Am\u00e9rica Latina.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticias.ulsaoaxaca.edu.mx\/index.php\/2024\/03\/11\/juntos-por-la-salud-infantil-equipo-de-erasmus-cielo-comparte-avances-en-reunion-virtual\/\" \/>\n<meta property=\"og:locale\" content=\"es_MX\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Juntos por la salud infantil: Equipo de ERASMUS+ CIELO comparte avances en reuni\u00f3n virtual\u00a0 - Noticias La Salle Oaxaca\" \/>\n<meta property=\"og:description\" content=\"Colaboradores de las 12 universidades que desarrollan el proyecto ERASMUS+ CIELO tuvieron su segunda reuni\u00f3n virtual para compartir avances de la propuesta que busca mejorar la salud infantil en Am\u00e9rica Latina.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticias.ulsaoaxaca.edu.mx\/index.php\/2024\/03\/11\/juntos-por-la-salud-infantil-equipo-de-erasmus-cielo-comparte-avances-en-reunion-virtual\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias La Salle Oaxaca\" \/>\n<meta property=\"article:published_time\" content=\"2024-03-11T23:21:54+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/noticias.ulsaoaxaca.edu.mx\/wp-content\/uploads\/2024\/03\/ERASMUS.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"800\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Lisset Miguel\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Lisset Miguel\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/noticias.ulsaoaxaca.edu.mx\\\/index.php\\\/2024\\\/03\\\/11\\\/juntos-por-la-salud-infantil-equipo-de-erasmus-cielo-comparte-avances-en-reunion-virtual\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/noticias.ulsaoaxaca.edu.mx\\\/index.php\\\/2024\\\/03\\\/11\\\/juntos-por-la-salud-infantil-equipo-de-erasmus-cielo-comparte-avances-en-reunion-virtual\\\/\"},\"author\":{\"name\":\"Lisset Miguel\",\"@id\":\"https:\\\/\\\/noticias.ulsaoaxaca.edu.mx\\\/#\\\/schema\\\/person\\\/81dae6da3a03a00481bfc01635dda099\"},\"headline\":\"Juntos por la salud infantil: Equipo de ERASMUS+ CIELO comparte avances en reuni\u00f3n virtual\u00a0\",\"datePublished\":\"2024-03-11T23:21:54+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/noticias.ulsaoaxaca.edu.mx\\\/index.php\\\/2024\\\/03\\\/11\\\/juntos-por-la-salud-infantil-equipo-de-erasmus-cielo-comparte-avances-en-reunion-virtual\\\/\"},\"wordCount\":494,\"image\":{\"@id\":\"https:\\\/\\\/noticias.ulsaoaxaca.edu.mx\\\/index.php\\\/2024\\\/03\\\/11\\\/juntos-por-la-salud-infantil-equipo-de-erasmus-cielo-comparte-avances-en-reunion-virtual\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/noticias.ulsaoaxaca.edu.mx\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/ERASMUS.jpg\",\"keywords\":[\"Investigaci\u00f3n\",\"licenciatura\"],\"articleSection\":[\"Investigaci\u00f3n\",\"Noticias\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/noticias.ulsaoaxaca.edu.mx\\\/index.php\\\/2024\\\/03\\\/11\\\/juntos-por-la-salud-infantil-equipo-de-erasmus-cielo-comparte-avances-en-reunion-virtual\\\/\",\"url\":\"https:\\\/\\\/noticias.ulsaoaxaca.edu.mx\\\/index.php\\\/2024\\\/03\\\/11\\\/juntos-por-la-salud-infantil-equipo-de-erasmus-cielo-comparte-avances-en-reunion-virtual\\\/\",\"name\":\"Juntos por la salud infantil: Equipo de ERASMUS+ CIELO comparte avances en reuni\u00f3n virtual\u00a0 - Noticias La Salle Oaxaca\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/noticias.ulsaoaxaca.edu.mx\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/noticias.ulsaoaxaca.edu.mx\\\/index.php\\\/2024\\\/03\\\/11\\\/juntos-por-la-salud-infantil-equipo-de-erasmus-cielo-comparte-avances-en-reunion-virtual\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/noticias.ulsaoaxaca.edu.mx\\\/index.php\\\/2024\\\/03\\\/11\\\/juntos-por-la-salud-infantil-equipo-de-erasmus-cielo-comparte-avances-en-reunion-virtual\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/noticias.ulsaoaxaca.edu.mx\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/ERASMUS.jpg\",\"datePublished\":\"2024-03-11T23:21:54+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/noticias.ulsaoaxaca.edu.mx\\\/#\\\/schema\\\/person\\\/81dae6da3a03a00481bfc01635dda099\"},\"description\":\"Colaboradores de las 12 universidades que desarrollan el proyecto ERASMUS+ CIELO tuvieron su segunda reuni\u00f3n virtual para compartir avances de la propuesta que busca mejorar la salud infantil en Am\u00e9rica Latina.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/noticias.ulsaoaxaca.edu.mx\\\/index.php\\\/2024\\\/03\\\/11\\\/juntos-por-la-salud-infantil-equipo-de-erasmus-cielo-comparte-avances-en-reunion-virtual\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/noticias.ulsaoaxaca.edu.mx\\\/index.php\\\/2024\\\/03\\\/11\\\/juntos-por-la-salud-infantil-equipo-de-erasmus-cielo-comparte-avances-en-reunion-virtual\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/noticias.ulsaoaxaca.edu.mx\\\/index.php\\\/2024\\\/03\\\/11\\\/juntos-por-la-salud-infantil-equipo-de-erasmus-cielo-comparte-avances-en-reunion-virtual\\\/#primaryimage\",\"url\":\"https:\\\/\\\/noticias.ulsaoaxaca.edu.mx\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/ERASMUS.jpg\",\"contentUrl\":\"https:\\\/\\\/noticias.ulsaoaxaca.edu.mx\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/ERASMUS.jpg\",\"width\":1200,\"height\":800},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/noticias.ulsaoaxaca.edu.mx\\\/index.php\\\/2024\\\/03\\\/11\\\/juntos-por-la-salud-infantil-equipo-de-erasmus-cielo-comparte-avances-en-reunion-virtual\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/noticias.ulsaoaxaca.edu.mx\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Juntos por la salud infantil: Equipo de ERASMUS+ CIELO comparte avances en reuni\u00f3n virtual\u00a0\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/noticias.ulsaoaxaca.edu.mx\\\/#website\",\"url\":\"https:\\\/\\\/noticias.ulsaoaxaca.edu.mx\\\/\",\"name\":\"Noticias La Salle Oaxaca\",\"description\":\"Noticias La Salle Oaxaca\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/noticias.ulsaoaxaca.edu.mx\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/noticias.ulsaoaxaca.edu.mx\\\/#\\\/schema\\\/person\\\/81dae6da3a03a00481bfc01635dda099\",\"name\":\"Lisset Miguel\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/acdd7a43156e9b483da8fc496c62783cb8098a66829aca2b993033e038fd7b13?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/acdd7a43156e9b483da8fc496c62783cb8098a66829aca2b993033e038fd7b13?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/acdd7a43156e9b483da8fc496c62783cb8098a66829aca2b993033e038fd7b13?s=96&d=mm&r=g\",\"caption\":\"Lisset Miguel\"},\"url\":\"https:\\\/\\\/noticias.ulsaoaxaca.edu.mx\\\/index.php\\\/author\\\/lisset-miguel\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Juntos por la salud infantil: Equipo de ERASMUS+ CIELO comparte avances en reuni\u00f3n virtual\u00a0 - Noticias La Salle Oaxaca","description":"Colaboradores de las 12 universidades que desarrollan el proyecto ERASMUS+ CIELO tuvieron su segunda reuni\u00f3n virtual para compartir avances de la propuesta que busca mejorar la salud infantil en Am\u00e9rica Latina.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticias.ulsaoaxaca.edu.mx\/index.php\/2024\/03\/11\/juntos-por-la-salud-infantil-equipo-de-erasmus-cielo-comparte-avances-en-reunion-virtual\/","og_locale":"es_MX","og_type":"article","og_title":"Juntos por la salud infantil: Equipo de ERASMUS+ CIELO comparte avances en reuni\u00f3n virtual\u00a0 - Noticias La Salle Oaxaca","og_description":"Colaboradores de las 12 universidades que desarrollan el proyecto ERASMUS+ CIELO tuvieron su segunda reuni\u00f3n virtual para compartir avances de la propuesta que busca mejorar la salud infantil en Am\u00e9rica Latina.","og_url":"https:\/\/noticias.ulsaoaxaca.edu.mx\/index.php\/2024\/03\/11\/juntos-por-la-salud-infantil-equipo-de-erasmus-cielo-comparte-avances-en-reunion-virtual\/","og_site_name":"Noticias La Salle Oaxaca","article_published_time":"2024-03-11T23:21:54+00:00","og_image":[{"width":1200,"height":800,"url":"https:\/\/noticias.ulsaoaxaca.edu.mx\/wp-content\/uploads\/2024\/03\/ERASMUS.jpg","type":"image\/jpeg"}],"author":"Lisset Miguel","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Lisset Miguel","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticias.ulsaoaxaca.edu.mx\/index.php\/2024\/03\/11\/juntos-por-la-salud-infantil-equipo-de-erasmus-cielo-comparte-avances-en-reunion-virtual\/#article","isPartOf":{"@id":"https:\/\/noticias.ulsaoaxaca.edu.mx\/index.php\/2024\/03\/11\/juntos-por-la-salud-infantil-equipo-de-erasmus-cielo-comparte-avances-en-reunion-virtual\/"},"author":{"name":"Lisset Miguel","@id":"https:\/\/noticias.ulsaoaxaca.edu.mx\/#\/schema\/person\/81dae6da3a03a00481bfc01635dda099"},"headline":"Juntos por la salud infantil: Equipo de ERASMUS+ CIELO comparte avances en reuni\u00f3n virtual\u00a0","datePublished":"2024-03-11T23:21:54+00:00","mainEntityOfPage":{"@id":"https:\/\/noticias.ulsaoaxaca.edu.mx\/index.php\/2024\/03\/11\/juntos-por-la-salud-infantil-equipo-de-erasmus-cielo-comparte-avances-en-reunion-virtual\/"},"wordCount":494,"image":{"@id":"https:\/\/noticias.ulsaoaxaca.edu.mx\/index.php\/2024\/03\/11\/juntos-por-la-salud-infantil-equipo-de-erasmus-cielo-comparte-avances-en-reunion-virtual\/#primaryimage"},"thumbnailUrl":"https:\/\/noticias.ulsaoaxaca.edu.mx\/wp-content\/uploads\/2024\/03\/ERASMUS.jpg","keywords":["Investigaci\u00f3n","licenciatura"],"articleSection":["Investigaci\u00f3n","Noticias"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/noticias.ulsaoaxaca.edu.mx\/index.php\/2024\/03\/11\/juntos-por-la-salud-infantil-equipo-de-erasmus-cielo-comparte-avances-en-reunion-virtual\/","url":"https:\/\/noticias.ulsaoaxaca.edu.mx\/index.php\/2024\/03\/11\/juntos-por-la-salud-infantil-equipo-de-erasmus-cielo-comparte-avances-en-reunion-virtual\/","name":"Juntos por la salud infantil: Equipo de ERASMUS+ CIELO comparte avances en reuni\u00f3n virtual\u00a0 - Noticias La Salle Oaxaca","isPartOf":{"@id":"https:\/\/noticias.ulsaoaxaca.edu.mx\/#website"},"primaryImageOfPage":{"@id":"https:\/\/noticias.ulsaoaxaca.edu.mx\/index.php\/2024\/03\/11\/juntos-por-la-salud-infantil-equipo-de-erasmus-cielo-comparte-avances-en-reunion-virtual\/#primaryimage"},"image":{"@id":"https:\/\/noticias.ulsaoaxaca.edu.mx\/index.php\/2024\/03\/11\/juntos-por-la-salud-infantil-equipo-de-erasmus-cielo-comparte-avances-en-reunion-virtual\/#primaryimage"},"thumbnailUrl":"https:\/\/noticias.ulsaoaxaca.edu.mx\/wp-content\/uploads\/2024\/03\/ERASMUS.jpg","datePublished":"2024-03-11T23:21:54+00:00","author":{"@id":"https:\/\/noticias.ulsaoaxaca.edu.mx\/#\/schema\/person\/81dae6da3a03a00481bfc01635dda099"},"description":"Colaboradores de las 12 universidades que desarrollan el proyecto ERASMUS+ CIELO tuvieron su segunda reuni\u00f3n virtual para compartir avances de la propuesta que busca mejorar la salud infantil en Am\u00e9rica Latina.","breadcrumb":{"@id":"https:\/\/noticias.ulsaoaxaca.edu.mx\/index.php\/2024\/03\/11\/juntos-por-la-salud-infantil-equipo-de-erasmus-cielo-comparte-avances-en-reunion-virtual\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticias.ulsaoaxaca.edu.mx\/index.php\/2024\/03\/11\/juntos-por-la-salud-infantil-equipo-de-erasmus-cielo-comparte-avances-en-reunion-virtual\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticias.ulsaoaxaca.edu.mx\/index.php\/2024\/03\/11\/juntos-por-la-salud-infantil-equipo-de-erasmus-cielo-comparte-avances-en-reunion-virtual\/#primaryimage","url":"https:\/\/noticias.ulsaoaxaca.edu.mx\/wp-content\/uploads\/2024\/03\/ERASMUS.jpg","contentUrl":"https:\/\/noticias.ulsaoaxaca.edu.mx\/wp-content\/uploads\/2024\/03\/ERASMUS.jpg","width":1200,"height":800},{"@type":"BreadcrumbList","@id":"https:\/\/noticias.ulsaoaxaca.edu.mx\/index.php\/2024\/03\/11\/juntos-por-la-salud-infantil-equipo-de-erasmus-cielo-comparte-avances-en-reunion-virtual\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/noticias.ulsaoaxaca.edu.mx\/"},{"@type":"ListItem","position":2,"name":"Juntos por la salud infantil: Equipo de ERASMUS+ CIELO comparte avances en reuni\u00f3n virtual\u00a0"}]},{"@type":"WebSite","@id":"https:\/\/noticias.ulsaoaxaca.edu.mx\/#website","url":"https:\/\/noticias.ulsaoaxaca.edu.mx\/","name":"Noticias La Salle Oaxaca","description":"Noticias La Salle Oaxaca","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticias.ulsaoaxaca.edu.mx\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/noticias.ulsaoaxaca.edu.mx\/#\/schema\/person\/81dae6da3a03a00481bfc01635dda099","name":"Lisset Miguel","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/acdd7a43156e9b483da8fc496c62783cb8098a66829aca2b993033e038fd7b13?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/acdd7a43156e9b483da8fc496c62783cb8098a66829aca2b993033e038fd7b13?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/acdd7a43156e9b483da8fc496c62783cb8098a66829aca2b993033e038fd7b13?s=96&d=mm&r=g","caption":"Lisset Miguel"},"url":"https:\/\/noticias.ulsaoaxaca.edu.mx\/index.php\/author\/lisset-miguel\/"}]}},"_links":{"self":[{"href":"https:\/\/noticias.ulsaoaxaca.edu.mx\/index.php\/wp-json\/wp\/v2\/posts\/40744","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticias.ulsaoaxaca.edu.mx\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticias.ulsaoaxaca.edu.mx\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/noticias.ulsaoaxaca.edu.mx\/index.php\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/noticias.ulsaoaxaca.edu.mx\/index.php\/wp-json\/wp\/v2\/comments?post=40744"}],"version-history":[{"count":9,"href":"https:\/\/noticias.ulsaoaxaca.edu.mx\/index.php\/wp-json\/wp\/v2\/posts\/40744\/revisions"}],"predecessor-version":[{"id":40754,"href":"https:\/\/noticias.ulsaoaxaca.edu.mx\/index.php\/wp-json\/wp\/v2\/posts\/40744\/revisions\/40754"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/noticias.ulsaoaxaca.edu.mx\/index.php\/wp-json\/wp\/v2\/media\/40745"}],"wp:attachment":[{"href":"https:\/\/noticias.ulsaoaxaca.edu.mx\/index.php\/wp-json\/wp\/v2\/media?parent=40744"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticias.ulsaoaxaca.edu.mx\/index.php\/wp-json\/wp\/v2\/categories?post=40744"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticias.ulsaoaxaca.edu.mx\/index.php\/wp-json\/wp\/v2\/tags?post=40744"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}