{"id":6529,"date":"2015-11-28T15:47:52","date_gmt":"2015-11-28T21:47:52","guid":{"rendered":"http:\/\/172.16.100.65\/wordpress_noticias\/?p=6529"},"modified":"2015-11-28T15:47:52","modified_gmt":"2015-11-28T21:47:52","slug":"feria-internacional-del-libro-se-presenta-en-universidad-la-salle-oaxaca","status":"publish","type":"post","link":"https:\/\/noticias.ulsaoaxaca.edu.mx\/index.php\/2015\/11\/28\/feria-internacional-del-libro-se-presenta-en-universidad-la-salle-oaxaca\/","title":{"rendered":"Feria Internacional del Libro, se presenta en Universidad La Salle Oaxaca"},"content":{"rendered":"<p>Con la finalidad de promover la lectura, as\u00ed como la interacci\u00f3n entre escritores y miembros de nuestra comunidad universitaria, del 26 al 30 de octubre diferentes escritores que participaron en la 35 Feria Internacional del Libro de Oaxaca, compartieron con alumnos, docentes y personal administrativo, sus experiencias como escritores y en algunos casos, aspectos fundamentales de sus obras m\u00e1s recientes.<\/p>\n<p>Elmer Mendoza, fue el primer escritor invitado, quien convers\u00f3 con los alumnos sobre su m\u00e9todo de escritura, as\u00ed como los aspectos fundamentales de su literatura, en donde destac\u00f3, el uso del lenguaje de la calle para crear una obra que toque la realidad que se vive en el pa\u00eds, desde sus or\u00edgenes.<\/p>\n<p>Durante el mismo d\u00eda, los periodistas Jos\u00e9 Luis Pardo, Pablo Ferri y Alejandra Inzunza, hablaron sobre su trabajo de investigaci\u00f3n period\u00edstico, en el que, a trav\u00e9s de diferentes viajes realizados por Suram\u00e9rica, obtuvieron informaci\u00f3n de primera mano, para explicar el fen\u00f3meno del narcotr\u00e1fico en ese territorio.<\/p>\n<p>El segundo d\u00eda, Joca Reiners, Paula Abrano, presentaron el libro \u201cLa tristeza extraordinaria\u201d, novela de Reiners, narrador brasile\u00f1o, cuya obra ha sido traducida al ingl\u00e9s y al espa\u00f1ol. De manera simult\u00e1nea, Mohsen Hmadi y Pilippe Oll\u00e9, compartieron con los alumnos sus experiencias como periodistas de investigaci\u00f3n y como defensores de la libertad de expresi\u00f3n en diferentes pa\u00edses del mundo.<\/p>\n<p>El \u00faltimo d\u00eda de actividades, los booktobers Rafael Cesa y Alberto Villarreal, hablaron sobre el trabajo que realizan para compartir rese\u00f1as de diferentes libros a trav\u00e9s de videos colocados en youtube, lo cual, en palabras de Alberto Villarreal, ayuda a que los j\u00f3venes puedan conocer de manera general libros que despierten su inter\u00e9s por la lectura.<\/p>\n<p>As\u00ed, alumnos de diferentes programas de estudio compartieron experiencias y opiniones con escritores de diferentes estilos y nacionalidades que participaron en el marco de la Feria Internacional del Libro de Oaxaca, para fomentar la cr\u00edtica, el di\u00e1logo y el inter\u00e9s por la lectura en sus diferentes modalidades.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Con la finalidad de promover la lectura, as\u00ed como la interacci\u00f3n entre escritores y miembros de nuestra comunidad universitaria, del 26 al 30 de octubre diferentes escritores que participaron en la 35 Feria Internacional del Libro de Oaxaca, compartieron con alumnos, docentes y personal administrativo, sus experiencias como escritores y en algunos casos, aspectos fundamentales &#8230;<\/p>\n","protected":false},"author":5,"featured_media":6530,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"image","meta":{"_acf_changed":false,"footnotes":""},"categories":[31],"tags":[86,92,91],"class_list":["post-6529","post","type-post","status-publish","format-image","has-post-thumbnail","hentry","category-noticias","tag-cultura","tag-feria-del-libro","tag-vinculacion","post_format-post-format-image"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Feria Internacional del Libro, se presenta en Universidad La Salle Oaxaca - Noticias La Salle Oaxaca<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticias.ulsaoaxaca.edu.mx\/index.php\/2015\/11\/28\/feria-internacional-del-libro-se-presenta-en-universidad-la-salle-oaxaca\/\" \/>\n<meta property=\"og:locale\" content=\"es_MX\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Feria Internacional del Libro, se presenta en Universidad La Salle Oaxaca - Noticias La Salle Oaxaca\" \/>\n<meta property=\"og:description\" content=\"Con la finalidad de promover la lectura, as\u00ed como la interacci\u00f3n entre escritores y miembros de nuestra comunidad universitaria, del 26 al 30 de octubre diferentes escritores que participaron en la 35 Feria Internacional del Libro de Oaxaca, compartieron con alumnos, docentes y personal administrativo, sus experiencias como escritores y en algunos casos, aspectos fundamentales ...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticias.ulsaoaxaca.edu.mx\/index.php\/2015\/11\/28\/feria-internacional-del-libro-se-presenta-en-universidad-la-salle-oaxaca\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias La Salle Oaxaca\" \/>\n<meta property=\"article:published_time\" content=\"2015-11-28T21:47:52+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/noticias.ulsaoaxaca.edu.mx\/wp-content\/uploads\/2015\/11\/IMG_1806.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"5184\" \/>\n\t<meta property=\"og:image:height\" content=\"3456\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Aym\u00e9 Giomara Barroso Loaeza\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Aym\u00e9 Giomara Barroso Loaeza\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/noticias.ulsaoaxaca.edu.mx\\\/index.php\\\/2015\\\/11\\\/28\\\/feria-internacional-del-libro-se-presenta-en-universidad-la-salle-oaxaca\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/noticias.ulsaoaxaca.edu.mx\\\/index.php\\\/2015\\\/11\\\/28\\\/feria-internacional-del-libro-se-presenta-en-universidad-la-salle-oaxaca\\\/\"},\"author\":{\"name\":\"Aym\u00e9 Giomara Barroso Loaeza\",\"@id\":\"https:\\\/\\\/noticias.ulsaoaxaca.edu.mx\\\/#\\\/schema\\\/person\\\/ab45430c6d904f5b8675f7505aaa8177\"},\"headline\":\"Feria Internacional del Libro, se presenta en Universidad La Salle Oaxaca\",\"datePublished\":\"2015-11-28T21:47:52+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/noticias.ulsaoaxaca.edu.mx\\\/index.php\\\/2015\\\/11\\\/28\\\/feria-internacional-del-libro-se-presenta-en-universidad-la-salle-oaxaca\\\/\"},\"wordCount\":357,\"image\":{\"@id\":\"https:\\\/\\\/noticias.ulsaoaxaca.edu.mx\\\/index.php\\\/2015\\\/11\\\/28\\\/feria-internacional-del-libro-se-presenta-en-universidad-la-salle-oaxaca\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/noticias.ulsaoaxaca.edu.mx\\\/wp-content\\\/uploads\\\/2015\\\/11\\\/IMG_1806.jpg\",\"keywords\":[\"cultura\",\"feria del libro\",\"vinculaci\u00f3n\"],\"articleSection\":[\"Noticias\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/noticias.ulsaoaxaca.edu.mx\\\/index.php\\\/2015\\\/11\\\/28\\\/feria-internacional-del-libro-se-presenta-en-universidad-la-salle-oaxaca\\\/\",\"url\":\"https:\\\/\\\/noticias.ulsaoaxaca.edu.mx\\\/index.php\\\/2015\\\/11\\\/28\\\/feria-internacional-del-libro-se-presenta-en-universidad-la-salle-oaxaca\\\/\",\"name\":\"Feria Internacional del Libro, se presenta en Universidad La Salle Oaxaca - Noticias La Salle Oaxaca\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/noticias.ulsaoaxaca.edu.mx\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/noticias.ulsaoaxaca.edu.mx\\\/index.php\\\/2015\\\/11\\\/28\\\/feria-internacional-del-libro-se-presenta-en-universidad-la-salle-oaxaca\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/noticias.ulsaoaxaca.edu.mx\\\/index.php\\\/2015\\\/11\\\/28\\\/feria-internacional-del-libro-se-presenta-en-universidad-la-salle-oaxaca\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/noticias.ulsaoaxaca.edu.mx\\\/wp-content\\\/uploads\\\/2015\\\/11\\\/IMG_1806.jpg\",\"datePublished\":\"2015-11-28T21:47:52+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/noticias.ulsaoaxaca.edu.mx\\\/#\\\/schema\\\/person\\\/ab45430c6d904f5b8675f7505aaa8177\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/noticias.ulsaoaxaca.edu.mx\\\/index.php\\\/2015\\\/11\\\/28\\\/feria-internacional-del-libro-se-presenta-en-universidad-la-salle-oaxaca\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/noticias.ulsaoaxaca.edu.mx\\\/index.php\\\/2015\\\/11\\\/28\\\/feria-internacional-del-libro-se-presenta-en-universidad-la-salle-oaxaca\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/noticias.ulsaoaxaca.edu.mx\\\/index.php\\\/2015\\\/11\\\/28\\\/feria-internacional-del-libro-se-presenta-en-universidad-la-salle-oaxaca\\\/#primaryimage\",\"url\":\"https:\\\/\\\/noticias.ulsaoaxaca.edu.mx\\\/wp-content\\\/uploads\\\/2015\\\/11\\\/IMG_1806.jpg\",\"contentUrl\":\"https:\\\/\\\/noticias.ulsaoaxaca.edu.mx\\\/wp-content\\\/uploads\\\/2015\\\/11\\\/IMG_1806.jpg\",\"width\":5184,\"height\":3456},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/noticias.ulsaoaxaca.edu.mx\\\/index.php\\\/2015\\\/11\\\/28\\\/feria-internacional-del-libro-se-presenta-en-universidad-la-salle-oaxaca\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/noticias.ulsaoaxaca.edu.mx\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Feria Internacional del Libro, se presenta en Universidad La Salle Oaxaca\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/noticias.ulsaoaxaca.edu.mx\\\/#website\",\"url\":\"https:\\\/\\\/noticias.ulsaoaxaca.edu.mx\\\/\",\"name\":\"Noticias La Salle Oaxaca\",\"description\":\"Noticias La Salle Oaxaca\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/noticias.ulsaoaxaca.edu.mx\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/noticias.ulsaoaxaca.edu.mx\\\/#\\\/schema\\\/person\\\/ab45430c6d904f5b8675f7505aaa8177\",\"name\":\"Aym\u00e9 Giomara Barroso Loaeza\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/51460040e636ad12076832b18ac69d4cc4ef2e4adaa24419d6900292d86a3ed3?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/51460040e636ad12076832b18ac69d4cc4ef2e4adaa24419d6900292d86a3ed3?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/51460040e636ad12076832b18ac69d4cc4ef2e4adaa24419d6900292d86a3ed3?s=96&d=mm&r=g\",\"caption\":\"Aym\u00e9 Giomara Barroso Loaeza\"},\"sameAs\":[\"http:\\\/\\\/ayme.barroso@ulsaoaxaca.edu.mx\"],\"url\":\"https:\\\/\\\/noticias.ulsaoaxaca.edu.mx\\\/index.php\\\/author\\\/area-comunicacion2\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Feria Internacional del Libro, se presenta en Universidad La Salle Oaxaca - Noticias La Salle Oaxaca","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticias.ulsaoaxaca.edu.mx\/index.php\/2015\/11\/28\/feria-internacional-del-libro-se-presenta-en-universidad-la-salle-oaxaca\/","og_locale":"es_MX","og_type":"article","og_title":"Feria Internacional del Libro, se presenta en Universidad La Salle Oaxaca - Noticias La Salle Oaxaca","og_description":"Con la finalidad de promover la lectura, as\u00ed como la interacci\u00f3n entre escritores y miembros de nuestra comunidad universitaria, del 26 al 30 de octubre diferentes escritores que participaron en la 35 Feria Internacional del Libro de Oaxaca, compartieron con alumnos, docentes y personal administrativo, sus experiencias como escritores y en algunos casos, aspectos fundamentales ...","og_url":"https:\/\/noticias.ulsaoaxaca.edu.mx\/index.php\/2015\/11\/28\/feria-internacional-del-libro-se-presenta-en-universidad-la-salle-oaxaca\/","og_site_name":"Noticias La Salle Oaxaca","article_published_time":"2015-11-28T21:47:52+00:00","og_image":[{"width":5184,"height":3456,"url":"https:\/\/noticias.ulsaoaxaca.edu.mx\/wp-content\/uploads\/2015\/11\/IMG_1806.jpg","type":"image\/jpeg"}],"author":"Aym\u00e9 Giomara Barroso Loaeza","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Aym\u00e9 Giomara Barroso Loaeza","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticias.ulsaoaxaca.edu.mx\/index.php\/2015\/11\/28\/feria-internacional-del-libro-se-presenta-en-universidad-la-salle-oaxaca\/#article","isPartOf":{"@id":"https:\/\/noticias.ulsaoaxaca.edu.mx\/index.php\/2015\/11\/28\/feria-internacional-del-libro-se-presenta-en-universidad-la-salle-oaxaca\/"},"author":{"name":"Aym\u00e9 Giomara Barroso Loaeza","@id":"https:\/\/noticias.ulsaoaxaca.edu.mx\/#\/schema\/person\/ab45430c6d904f5b8675f7505aaa8177"},"headline":"Feria Internacional del Libro, se presenta en Universidad La Salle Oaxaca","datePublished":"2015-11-28T21:47:52+00:00","mainEntityOfPage":{"@id":"https:\/\/noticias.ulsaoaxaca.edu.mx\/index.php\/2015\/11\/28\/feria-internacional-del-libro-se-presenta-en-universidad-la-salle-oaxaca\/"},"wordCount":357,"image":{"@id":"https:\/\/noticias.ulsaoaxaca.edu.mx\/index.php\/2015\/11\/28\/feria-internacional-del-libro-se-presenta-en-universidad-la-salle-oaxaca\/#primaryimage"},"thumbnailUrl":"https:\/\/noticias.ulsaoaxaca.edu.mx\/wp-content\/uploads\/2015\/11\/IMG_1806.jpg","keywords":["cultura","feria del libro","vinculaci\u00f3n"],"articleSection":["Noticias"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/noticias.ulsaoaxaca.edu.mx\/index.php\/2015\/11\/28\/feria-internacional-del-libro-se-presenta-en-universidad-la-salle-oaxaca\/","url":"https:\/\/noticias.ulsaoaxaca.edu.mx\/index.php\/2015\/11\/28\/feria-internacional-del-libro-se-presenta-en-universidad-la-salle-oaxaca\/","name":"Feria Internacional del Libro, se presenta en Universidad La Salle Oaxaca - Noticias La Salle Oaxaca","isPartOf":{"@id":"https:\/\/noticias.ulsaoaxaca.edu.mx\/#website"},"primaryImageOfPage":{"@id":"https:\/\/noticias.ulsaoaxaca.edu.mx\/index.php\/2015\/11\/28\/feria-internacional-del-libro-se-presenta-en-universidad-la-salle-oaxaca\/#primaryimage"},"image":{"@id":"https:\/\/noticias.ulsaoaxaca.edu.mx\/index.php\/2015\/11\/28\/feria-internacional-del-libro-se-presenta-en-universidad-la-salle-oaxaca\/#primaryimage"},"thumbnailUrl":"https:\/\/noticias.ulsaoaxaca.edu.mx\/wp-content\/uploads\/2015\/11\/IMG_1806.jpg","datePublished":"2015-11-28T21:47:52+00:00","author":{"@id":"https:\/\/noticias.ulsaoaxaca.edu.mx\/#\/schema\/person\/ab45430c6d904f5b8675f7505aaa8177"},"breadcrumb":{"@id":"https:\/\/noticias.ulsaoaxaca.edu.mx\/index.php\/2015\/11\/28\/feria-internacional-del-libro-se-presenta-en-universidad-la-salle-oaxaca\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticias.ulsaoaxaca.edu.mx\/index.php\/2015\/11\/28\/feria-internacional-del-libro-se-presenta-en-universidad-la-salle-oaxaca\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticias.ulsaoaxaca.edu.mx\/index.php\/2015\/11\/28\/feria-internacional-del-libro-se-presenta-en-universidad-la-salle-oaxaca\/#primaryimage","url":"https:\/\/noticias.ulsaoaxaca.edu.mx\/wp-content\/uploads\/2015\/11\/IMG_1806.jpg","contentUrl":"https:\/\/noticias.ulsaoaxaca.edu.mx\/wp-content\/uploads\/2015\/11\/IMG_1806.jpg","width":5184,"height":3456},{"@type":"BreadcrumbList","@id":"https:\/\/noticias.ulsaoaxaca.edu.mx\/index.php\/2015\/11\/28\/feria-internacional-del-libro-se-presenta-en-universidad-la-salle-oaxaca\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/noticias.ulsaoaxaca.edu.mx\/"},{"@type":"ListItem","position":2,"name":"Feria Internacional del Libro, se presenta en Universidad La Salle Oaxaca"}]},{"@type":"WebSite","@id":"https:\/\/noticias.ulsaoaxaca.edu.mx\/#website","url":"https:\/\/noticias.ulsaoaxaca.edu.mx\/","name":"Noticias La Salle Oaxaca","description":"Noticias La Salle Oaxaca","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticias.ulsaoaxaca.edu.mx\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/noticias.ulsaoaxaca.edu.mx\/#\/schema\/person\/ab45430c6d904f5b8675f7505aaa8177","name":"Aym\u00e9 Giomara Barroso Loaeza","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/51460040e636ad12076832b18ac69d4cc4ef2e4adaa24419d6900292d86a3ed3?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/51460040e636ad12076832b18ac69d4cc4ef2e4adaa24419d6900292d86a3ed3?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/51460040e636ad12076832b18ac69d4cc4ef2e4adaa24419d6900292d86a3ed3?s=96&d=mm&r=g","caption":"Aym\u00e9 Giomara Barroso Loaeza"},"sameAs":["http:\/\/ayme.barroso@ulsaoaxaca.edu.mx"],"url":"https:\/\/noticias.ulsaoaxaca.edu.mx\/index.php\/author\/area-comunicacion2\/"}]}},"_links":{"self":[{"href":"https:\/\/noticias.ulsaoaxaca.edu.mx\/index.php\/wp-json\/wp\/v2\/posts\/6529","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticias.ulsaoaxaca.edu.mx\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticias.ulsaoaxaca.edu.mx\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/noticias.ulsaoaxaca.edu.mx\/index.php\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/noticias.ulsaoaxaca.edu.mx\/index.php\/wp-json\/wp\/v2\/comments?post=6529"}],"version-history":[{"count":2,"href":"https:\/\/noticias.ulsaoaxaca.edu.mx\/index.php\/wp-json\/wp\/v2\/posts\/6529\/revisions"}],"predecessor-version":[{"id":6532,"href":"https:\/\/noticias.ulsaoaxaca.edu.mx\/index.php\/wp-json\/wp\/v2\/posts\/6529\/revisions\/6532"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/noticias.ulsaoaxaca.edu.mx\/index.php\/wp-json\/wp\/v2\/media\/6530"}],"wp:attachment":[{"href":"https:\/\/noticias.ulsaoaxaca.edu.mx\/index.php\/wp-json\/wp\/v2\/media?parent=6529"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticias.ulsaoaxaca.edu.mx\/index.php\/wp-json\/wp\/v2\/categories?post=6529"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticias.ulsaoaxaca.edu.mx\/index.php\/wp-json\/wp\/v2\/tags?post=6529"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}