{"id":7903,"date":"2016-08-09T19:23:46","date_gmt":"2016-08-10T00:23:46","guid":{"rendered":"http:\/\/noticias.ulsaoaxaca.edu.mx\/?p=7903"},"modified":"2016-08-09T19:24:19","modified_gmt":"2016-08-10T00:24:19","slug":"dr-abraham-nosnik-participa-en-ciclo-conferencias-especializadas-la-salle-oaxaca","status":"publish","type":"post","link":"https:\/\/noticias.ulsaoaxaca.edu.mx\/index.php\/2016\/08\/09\/dr-abraham-nosnik-participa-en-ciclo-conferencias-especializadas-la-salle-oaxaca\/","title":{"rendered":"Dr. Abraham Nosnik participa en Ciclo de Conferencias Especializadas de La Salle Oaxaca"},"content":{"rendered":"<p>\u201cLa utilidad social de la comunicaci\u00f3n y el costo de la incomunicaci\u00f3n\u201d, fue el t\u00edtulo de la conferencia impartida por el doctor Abraham Nosnik, en nuestra Universidad, como parte de las actividades programadas en el Ciclo de Conferencias Especializadas, organizado por el \u00e1rea de Posgrado de manera cuatrimestral, que tiene como finalidad impartir a modo de c\u00e1tedra abierta, conferencias que aborden temas de inter\u00e9s y vigencia significativa relacionadas con los programas de maestr\u00eda con los que cuenta la Universidad La Salle Oaxaca.<\/p>\n<p>De este modo, el pasado 06 de agosto, toc\u00f3 el turno al especialista, investigador y consultor en comunicaci\u00f3n organizacional y comunicaci\u00f3n estrat\u00e9gica, Abraham Nosnik, que comparti\u00f3 con maestrantes e invitados externos a nuestra comunidad la necesidad de pensar en procesos de comunicaci\u00f3n que tomen en cuenta los costos sociales y econ\u00f3micos de sus decisiones.<\/p>\n<p>Por ello durante su ponencia el doctor Nosnik invit\u00f3 a los asistentes a reflexionar en que a mayor profesionalizaci\u00f3n de los actores de la comunicaci\u00f3n el beneficio social que se lograr\u00e1 con ello ser\u00e1 mucho mayor y podr\u00e1 traducirse gradualmente en mejores oportunidades de desarrollo a nivel local y nacional.<\/p>\n<p>Para contribuir a esta profesionalizaci\u00f3n, destac\u00f3 la importancia de mantener una visi\u00f3n del pa\u00eds a largo plazo, as\u00ed como el sentido del prop\u00f3sito para llevar a cabo esa visi\u00f3n de la mano con el fomento a la investigaci\u00f3n y la innovaci\u00f3n en todo el territorio.<\/p>\n<p>Respecto a la responsabilidad social de los profesionales de la comunicaci\u00f3n, el doctor Nosnik, resalt\u00f3 valores como la integridad personal, la \u00e9tica profesional y la responsabilidad individual ante el sistema, como un abanico de elementos que aportan positivamente a la consolidaci\u00f3n de la reputaci\u00f3n nacional como un espacio de desarrollo en diversos sectores.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u201cLa utilidad social de la comunicaci\u00f3n y el costo de la incomunicaci\u00f3n\u201d, fue el t\u00edtulo de la conferencia impartida por el doctor Abraham Nosnik, en nuestra Universidad, como parte de las actividades programadas en el Ciclo de Conferencias Especializadas, organizado por el \u00e1rea de Posgrado de manera cuatrimestral, que tiene como finalidad impartir a modo &#8230;<\/p>\n","protected":false},"author":5,"featured_media":7906,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"gallery","meta":{"_acf_changed":false,"footnotes":""},"categories":[42],"tags":[125],"class_list":["post-7903","post","type-post","status-publish","format-gallery","has-post-thumbnail","hentry","category-galerias","tag-posgrado","post_format-post-format-gallery"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Dr. Abraham Nosnik participa en Ciclo de Conferencias Especializadas de La Salle Oaxaca - Noticias La Salle Oaxaca<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticias.ulsaoaxaca.edu.mx\/index.php\/2016\/08\/09\/dr-abraham-nosnik-participa-en-ciclo-conferencias-especializadas-la-salle-oaxaca\/\" \/>\n<meta property=\"og:locale\" content=\"es_MX\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Dr. Abraham Nosnik participa en Ciclo de Conferencias Especializadas de La Salle Oaxaca - Noticias La Salle Oaxaca\" \/>\n<meta property=\"og:description\" content=\"\u201cLa utilidad social de la comunicaci\u00f3n y el costo de la incomunicaci\u00f3n\u201d, fue el t\u00edtulo de la conferencia impartida por el doctor Abraham Nosnik, en nuestra Universidad, como parte de las actividades programadas en el Ciclo de Conferencias Especializadas, organizado por el \u00e1rea de Posgrado de manera cuatrimestral, que tiene como finalidad impartir a modo ...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticias.ulsaoaxaca.edu.mx\/index.php\/2016\/08\/09\/dr-abraham-nosnik-participa-en-ciclo-conferencias-especializadas-la-salle-oaxaca\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias La Salle Oaxaca\" \/>\n<meta property=\"article:published_time\" content=\"2016-08-10T00:23:46+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2016-08-10T00:24:19+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/noticias.ulsaoaxaca.edu.mx\/wp-content\/uploads\/2016\/08\/MG_9768.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"5184\" \/>\n\t<meta property=\"og:image:height\" content=\"3456\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Aym\u00e9 Giomara Barroso Loaeza\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Aym\u00e9 Giomara Barroso Loaeza\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/noticias.ulsaoaxaca.edu.mx\\\/index.php\\\/2016\\\/08\\\/09\\\/dr-abraham-nosnik-participa-en-ciclo-conferencias-especializadas-la-salle-oaxaca\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/noticias.ulsaoaxaca.edu.mx\\\/index.php\\\/2016\\\/08\\\/09\\\/dr-abraham-nosnik-participa-en-ciclo-conferencias-especializadas-la-salle-oaxaca\\\/\"},\"author\":{\"name\":\"Aym\u00e9 Giomara Barroso Loaeza\",\"@id\":\"https:\\\/\\\/noticias.ulsaoaxaca.edu.mx\\\/#\\\/schema\\\/person\\\/ab45430c6d904f5b8675f7505aaa8177\"},\"headline\":\"Dr. Abraham Nosnik participa en Ciclo de Conferencias Especializadas de La Salle Oaxaca\",\"datePublished\":\"2016-08-10T00:23:46+00:00\",\"dateModified\":\"2016-08-10T00:24:19+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/noticias.ulsaoaxaca.edu.mx\\\/index.php\\\/2016\\\/08\\\/09\\\/dr-abraham-nosnik-participa-en-ciclo-conferencias-especializadas-la-salle-oaxaca\\\/\"},\"wordCount\":319,\"image\":{\"@id\":\"https:\\\/\\\/noticias.ulsaoaxaca.edu.mx\\\/index.php\\\/2016\\\/08\\\/09\\\/dr-abraham-nosnik-participa-en-ciclo-conferencias-especializadas-la-salle-oaxaca\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/noticias.ulsaoaxaca.edu.mx\\\/wp-content\\\/uploads\\\/2016\\\/08\\\/MG_9768.jpg\",\"keywords\":[\"posgrado\"],\"articleSection\":[\"Galerias\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/noticias.ulsaoaxaca.edu.mx\\\/index.php\\\/2016\\\/08\\\/09\\\/dr-abraham-nosnik-participa-en-ciclo-conferencias-especializadas-la-salle-oaxaca\\\/\",\"url\":\"https:\\\/\\\/noticias.ulsaoaxaca.edu.mx\\\/index.php\\\/2016\\\/08\\\/09\\\/dr-abraham-nosnik-participa-en-ciclo-conferencias-especializadas-la-salle-oaxaca\\\/\",\"name\":\"Dr. Abraham Nosnik participa en Ciclo de Conferencias Especializadas de La Salle Oaxaca - Noticias La Salle Oaxaca\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/noticias.ulsaoaxaca.edu.mx\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/noticias.ulsaoaxaca.edu.mx\\\/index.php\\\/2016\\\/08\\\/09\\\/dr-abraham-nosnik-participa-en-ciclo-conferencias-especializadas-la-salle-oaxaca\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/noticias.ulsaoaxaca.edu.mx\\\/index.php\\\/2016\\\/08\\\/09\\\/dr-abraham-nosnik-participa-en-ciclo-conferencias-especializadas-la-salle-oaxaca\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/noticias.ulsaoaxaca.edu.mx\\\/wp-content\\\/uploads\\\/2016\\\/08\\\/MG_9768.jpg\",\"datePublished\":\"2016-08-10T00:23:46+00:00\",\"dateModified\":\"2016-08-10T00:24:19+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/noticias.ulsaoaxaca.edu.mx\\\/#\\\/schema\\\/person\\\/ab45430c6d904f5b8675f7505aaa8177\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/noticias.ulsaoaxaca.edu.mx\\\/index.php\\\/2016\\\/08\\\/09\\\/dr-abraham-nosnik-participa-en-ciclo-conferencias-especializadas-la-salle-oaxaca\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/noticias.ulsaoaxaca.edu.mx\\\/index.php\\\/2016\\\/08\\\/09\\\/dr-abraham-nosnik-participa-en-ciclo-conferencias-especializadas-la-salle-oaxaca\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/noticias.ulsaoaxaca.edu.mx\\\/index.php\\\/2016\\\/08\\\/09\\\/dr-abraham-nosnik-participa-en-ciclo-conferencias-especializadas-la-salle-oaxaca\\\/#primaryimage\",\"url\":\"https:\\\/\\\/noticias.ulsaoaxaca.edu.mx\\\/wp-content\\\/uploads\\\/2016\\\/08\\\/MG_9768.jpg\",\"contentUrl\":\"https:\\\/\\\/noticias.ulsaoaxaca.edu.mx\\\/wp-content\\\/uploads\\\/2016\\\/08\\\/MG_9768.jpg\",\"width\":5184,\"height\":3456},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/noticias.ulsaoaxaca.edu.mx\\\/index.php\\\/2016\\\/08\\\/09\\\/dr-abraham-nosnik-participa-en-ciclo-conferencias-especializadas-la-salle-oaxaca\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/noticias.ulsaoaxaca.edu.mx\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Dr. Abraham Nosnik participa en Ciclo de Conferencias Especializadas de La Salle Oaxaca\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/noticias.ulsaoaxaca.edu.mx\\\/#website\",\"url\":\"https:\\\/\\\/noticias.ulsaoaxaca.edu.mx\\\/\",\"name\":\"Noticias La Salle Oaxaca\",\"description\":\"Noticias La Salle Oaxaca\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/noticias.ulsaoaxaca.edu.mx\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/noticias.ulsaoaxaca.edu.mx\\\/#\\\/schema\\\/person\\\/ab45430c6d904f5b8675f7505aaa8177\",\"name\":\"Aym\u00e9 Giomara Barroso Loaeza\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/51460040e636ad12076832b18ac69d4cc4ef2e4adaa24419d6900292d86a3ed3?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/51460040e636ad12076832b18ac69d4cc4ef2e4adaa24419d6900292d86a3ed3?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/51460040e636ad12076832b18ac69d4cc4ef2e4adaa24419d6900292d86a3ed3?s=96&d=mm&r=g\",\"caption\":\"Aym\u00e9 Giomara Barroso Loaeza\"},\"sameAs\":[\"http:\\\/\\\/ayme.barroso@ulsaoaxaca.edu.mx\"],\"url\":\"https:\\\/\\\/noticias.ulsaoaxaca.edu.mx\\\/index.php\\\/author\\\/area-comunicacion2\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Dr. Abraham Nosnik participa en Ciclo de Conferencias Especializadas de La Salle Oaxaca - Noticias La Salle Oaxaca","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticias.ulsaoaxaca.edu.mx\/index.php\/2016\/08\/09\/dr-abraham-nosnik-participa-en-ciclo-conferencias-especializadas-la-salle-oaxaca\/","og_locale":"es_MX","og_type":"article","og_title":"Dr. Abraham Nosnik participa en Ciclo de Conferencias Especializadas de La Salle Oaxaca - Noticias La Salle Oaxaca","og_description":"\u201cLa utilidad social de la comunicaci\u00f3n y el costo de la incomunicaci\u00f3n\u201d, fue el t\u00edtulo de la conferencia impartida por el doctor Abraham Nosnik, en nuestra Universidad, como parte de las actividades programadas en el Ciclo de Conferencias Especializadas, organizado por el \u00e1rea de Posgrado de manera cuatrimestral, que tiene como finalidad impartir a modo ...","og_url":"https:\/\/noticias.ulsaoaxaca.edu.mx\/index.php\/2016\/08\/09\/dr-abraham-nosnik-participa-en-ciclo-conferencias-especializadas-la-salle-oaxaca\/","og_site_name":"Noticias La Salle Oaxaca","article_published_time":"2016-08-10T00:23:46+00:00","article_modified_time":"2016-08-10T00:24:19+00:00","og_image":[{"width":5184,"height":3456,"url":"https:\/\/noticias.ulsaoaxaca.edu.mx\/wp-content\/uploads\/2016\/08\/MG_9768.jpg","type":"image\/jpeg"}],"author":"Aym\u00e9 Giomara Barroso Loaeza","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Aym\u00e9 Giomara Barroso Loaeza","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticias.ulsaoaxaca.edu.mx\/index.php\/2016\/08\/09\/dr-abraham-nosnik-participa-en-ciclo-conferencias-especializadas-la-salle-oaxaca\/#article","isPartOf":{"@id":"https:\/\/noticias.ulsaoaxaca.edu.mx\/index.php\/2016\/08\/09\/dr-abraham-nosnik-participa-en-ciclo-conferencias-especializadas-la-salle-oaxaca\/"},"author":{"name":"Aym\u00e9 Giomara Barroso Loaeza","@id":"https:\/\/noticias.ulsaoaxaca.edu.mx\/#\/schema\/person\/ab45430c6d904f5b8675f7505aaa8177"},"headline":"Dr. Abraham Nosnik participa en Ciclo de Conferencias Especializadas de La Salle Oaxaca","datePublished":"2016-08-10T00:23:46+00:00","dateModified":"2016-08-10T00:24:19+00:00","mainEntityOfPage":{"@id":"https:\/\/noticias.ulsaoaxaca.edu.mx\/index.php\/2016\/08\/09\/dr-abraham-nosnik-participa-en-ciclo-conferencias-especializadas-la-salle-oaxaca\/"},"wordCount":319,"image":{"@id":"https:\/\/noticias.ulsaoaxaca.edu.mx\/index.php\/2016\/08\/09\/dr-abraham-nosnik-participa-en-ciclo-conferencias-especializadas-la-salle-oaxaca\/#primaryimage"},"thumbnailUrl":"https:\/\/noticias.ulsaoaxaca.edu.mx\/wp-content\/uploads\/2016\/08\/MG_9768.jpg","keywords":["posgrado"],"articleSection":["Galerias"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/noticias.ulsaoaxaca.edu.mx\/index.php\/2016\/08\/09\/dr-abraham-nosnik-participa-en-ciclo-conferencias-especializadas-la-salle-oaxaca\/","url":"https:\/\/noticias.ulsaoaxaca.edu.mx\/index.php\/2016\/08\/09\/dr-abraham-nosnik-participa-en-ciclo-conferencias-especializadas-la-salle-oaxaca\/","name":"Dr. Abraham Nosnik participa en Ciclo de Conferencias Especializadas de La Salle Oaxaca - Noticias La Salle Oaxaca","isPartOf":{"@id":"https:\/\/noticias.ulsaoaxaca.edu.mx\/#website"},"primaryImageOfPage":{"@id":"https:\/\/noticias.ulsaoaxaca.edu.mx\/index.php\/2016\/08\/09\/dr-abraham-nosnik-participa-en-ciclo-conferencias-especializadas-la-salle-oaxaca\/#primaryimage"},"image":{"@id":"https:\/\/noticias.ulsaoaxaca.edu.mx\/index.php\/2016\/08\/09\/dr-abraham-nosnik-participa-en-ciclo-conferencias-especializadas-la-salle-oaxaca\/#primaryimage"},"thumbnailUrl":"https:\/\/noticias.ulsaoaxaca.edu.mx\/wp-content\/uploads\/2016\/08\/MG_9768.jpg","datePublished":"2016-08-10T00:23:46+00:00","dateModified":"2016-08-10T00:24:19+00:00","author":{"@id":"https:\/\/noticias.ulsaoaxaca.edu.mx\/#\/schema\/person\/ab45430c6d904f5b8675f7505aaa8177"},"breadcrumb":{"@id":"https:\/\/noticias.ulsaoaxaca.edu.mx\/index.php\/2016\/08\/09\/dr-abraham-nosnik-participa-en-ciclo-conferencias-especializadas-la-salle-oaxaca\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticias.ulsaoaxaca.edu.mx\/index.php\/2016\/08\/09\/dr-abraham-nosnik-participa-en-ciclo-conferencias-especializadas-la-salle-oaxaca\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticias.ulsaoaxaca.edu.mx\/index.php\/2016\/08\/09\/dr-abraham-nosnik-participa-en-ciclo-conferencias-especializadas-la-salle-oaxaca\/#primaryimage","url":"https:\/\/noticias.ulsaoaxaca.edu.mx\/wp-content\/uploads\/2016\/08\/MG_9768.jpg","contentUrl":"https:\/\/noticias.ulsaoaxaca.edu.mx\/wp-content\/uploads\/2016\/08\/MG_9768.jpg","width":5184,"height":3456},{"@type":"BreadcrumbList","@id":"https:\/\/noticias.ulsaoaxaca.edu.mx\/index.php\/2016\/08\/09\/dr-abraham-nosnik-participa-en-ciclo-conferencias-especializadas-la-salle-oaxaca\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/noticias.ulsaoaxaca.edu.mx\/"},{"@type":"ListItem","position":2,"name":"Dr. Abraham Nosnik participa en Ciclo de Conferencias Especializadas de La Salle Oaxaca"}]},{"@type":"WebSite","@id":"https:\/\/noticias.ulsaoaxaca.edu.mx\/#website","url":"https:\/\/noticias.ulsaoaxaca.edu.mx\/","name":"Noticias La Salle Oaxaca","description":"Noticias La Salle Oaxaca","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticias.ulsaoaxaca.edu.mx\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/noticias.ulsaoaxaca.edu.mx\/#\/schema\/person\/ab45430c6d904f5b8675f7505aaa8177","name":"Aym\u00e9 Giomara Barroso Loaeza","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/51460040e636ad12076832b18ac69d4cc4ef2e4adaa24419d6900292d86a3ed3?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/51460040e636ad12076832b18ac69d4cc4ef2e4adaa24419d6900292d86a3ed3?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/51460040e636ad12076832b18ac69d4cc4ef2e4adaa24419d6900292d86a3ed3?s=96&d=mm&r=g","caption":"Aym\u00e9 Giomara Barroso Loaeza"},"sameAs":["http:\/\/ayme.barroso@ulsaoaxaca.edu.mx"],"url":"https:\/\/noticias.ulsaoaxaca.edu.mx\/index.php\/author\/area-comunicacion2\/"}]}},"_links":{"self":[{"href":"https:\/\/noticias.ulsaoaxaca.edu.mx\/index.php\/wp-json\/wp\/v2\/posts\/7903","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticias.ulsaoaxaca.edu.mx\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticias.ulsaoaxaca.edu.mx\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/noticias.ulsaoaxaca.edu.mx\/index.php\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/noticias.ulsaoaxaca.edu.mx\/index.php\/wp-json\/wp\/v2\/comments?post=7903"}],"version-history":[{"count":1,"href":"https:\/\/noticias.ulsaoaxaca.edu.mx\/index.php\/wp-json\/wp\/v2\/posts\/7903\/revisions"}],"predecessor-version":[{"id":7910,"href":"https:\/\/noticias.ulsaoaxaca.edu.mx\/index.php\/wp-json\/wp\/v2\/posts\/7903\/revisions\/7910"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/noticias.ulsaoaxaca.edu.mx\/index.php\/wp-json\/wp\/v2\/media\/7906"}],"wp:attachment":[{"href":"https:\/\/noticias.ulsaoaxaca.edu.mx\/index.php\/wp-json\/wp\/v2\/media?parent=7903"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticias.ulsaoaxaca.edu.mx\/index.php\/wp-json\/wp\/v2\/categories?post=7903"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticias.ulsaoaxaca.edu.mx\/index.php\/wp-json\/wp\/v2\/tags?post=7903"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}